{"id":11470,"date":"2025-02-25T15:42:52","date_gmt":"2025-02-25T14:42:52","guid":{"rendered":"https:\/\/azvitrine.ecdev.fr\/?post_type=fiche-ete&#038;p=11470"},"modified":"2026-08-31T14:42:04","modified_gmt":"2026-08-31T12:42:04","slug":"hotel-gorges-du-tarn","status":"publish","type":"fiche-ete","link":"https:\/\/www.azureva-vacances.com\/fr\/hebergement\/hotel-gorges-du-tarn\/","title":{"rendered":"Gorges du Tarn &#8211; Les Bateliers"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11470\" class=\"elementor elementor-11470\" data-elementor-post-type=\"fiche-ete\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ca6b61 e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"9ca6b61\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-03f6e90 elementor-widget elementor-widget-text-editor\" data-id=\"03f6e90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span style=\"color: #00a650;\">Activit\u00e9s pour tous : amusement et \u00e9vasion en famille !<\/span><\/h3><p style=\"text-align: justify;\">L&#8217;h\u00f4tel Les Bateliers &#8211; La Mal\u00e8ne vous r\u00e9serve un large choix d&#8217;activit\u00e9s pour toute la famille. Balades, d\u00e9couvertes nature, moments de d\u00e9tente&#8230; De quoi profiter pleinement des Gorges du Tarn sans regarder l&#8217;heure. Vous \u00eates en vacances, apr\u00e8s tout !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-664ac6b e-con-full responsive-scroll elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"664ac6b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-adb247e e-con-full e-flex e-con e-child\" data-id=\"adb247e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-93ced2b e-transform elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"93ced2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scaleX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.azureva-vacances.com\/wp-content\/uploads\/2025\/02\/583d4a0350add_vacances-velo-la-malene-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-15778\" alt=\"le velo en vacances a la malene\u00a0\" srcset=\"https:\/\/www.azureva-vacances.com\/wp-content\/uploads\/2025\/02\/583d4a0350add_vacances-velo-la-malene-mobile.avif 420w\" sizes=\"auto, (max-width: 420px) 100vw, 100vw\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77f7cff elementor-widget elementor-widget-text-editor\" data-id=\"77f7cff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: justify;\">LOISIRS<\/h3><p style=\"text-align: justify;\"><span style=\"color: #00a650;\">EN OPTION<\/span><\/p><p style=\"text-align: justify;\">Balades ou petites randonn\u00e9es p\u00e9destres. P\u00eache \u00e0 la mouche, au lancer\u2026<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e7e5a13 e-con-full e-flex e-con e-child\" data-id=\"e7e5a13\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b0b87a e-transform elementor-widget elementor-widget-image\" data-id=\"7b0b87a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scaleX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.azureva-vacances.com\/wp-content\/uploads\/2025\/02\/583d4b46e48e6_location-vacances-campagne-la-malene-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-15790\" alt=\"la location vacances la malene campagne\u00a0\" srcset=\"https:\/\/www.azureva-vacances.com\/wp-content\/uploads\/2025\/02\/583d4b46e48e6_location-vacances-campagne-la-malene-mobile.avif 420w\" sizes=\"auto, (max-width: 420px) 100vw, 100vw\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c72764e elementor-widget elementor-widget-text-editor\" data-id=\"c72764e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: justify;\">MULTI-ACTIVIT\u00c9S FESTIVES<\/h3><p style=\"text-align: justify;\"><span style=\"color: #00a650;\">EN OPTION<\/span><\/p><p style=\"text-align: justify;\">Sports d\u2019eaux vives : cano\u00eb-kayak, Piscine couverte \u00e0 Millau. Sp\u00e9l\u00e9ologie, Escalade. Via Ferrata Accrobranches Saut \u00e0 l&#8217;\u00e9lastique Parapente<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c931ac e-con-full e-flex e-con e-child\" data-id=\"6c931ac\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d3cf04 e-transform elementor-widget elementor-widget-image\" data-id=\"8d3cf04\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_scaleX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_scaleY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"390\" height=\"390\" src=\"https:\/\/www.azureva-vacances.com\/wp-content\/uploads\/2025\/02\/583d4b37824a8_location-vacances-decouverte-la-malene.jpg\" class=\"attachment-large size-large wp-image-15784\" alt=\"decouverte location de vacances la malene\u00a0\" srcset=\"https:\/\/www.azureva-vacances.com\/wp-content\/uploads\/2025\/02\/583d4b37824a8_location-vacances-decouverte-la-malene-mobile.avif 420w\" sizes=\"auto, (max-width: 420px) 100vw, 100vw\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6144e7 elementor-widget elementor-widget-text-editor\" data-id=\"f6144e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: justify;\">DECOUVERTE DU TERROIR<\/h3><header class=\"villageCard__bodyHeader\"><div class=\"activitiesCard__title\" style=\"text-align: left;\"><span style=\"color: #00a650;\">EN OPTION<\/span><\/div><div>\u00a0<\/div><div style=\"text-align: justify;\"><article id=\"tns2-item4\" class=\"villageCard__container tns-item tns-slide-active\"><main class=\"villageCard__body\"><main class=\"villageCard__bodyContent\"><div class=\"activitiesCard__desc\"><p>Randonn\u00e9es avec guide de moyenne montagne, Promenades \u00e0 cheval, Descente en barque avec les bateliers de La Mal\u00e8ne, Cano\u00eb-kayak, Visite de la ville de Millau et vue sur le viaduc, Les caves de Roquefort, Les grottes de l\u2019Aven Armand et de Dargilan, L&#8217;ab\u00eeme de Bramabiau, site des chaos de Montpellier le Vieux, La cit\u00e9 m\u00e9di\u00e9vale de Sainte-Enimie, La Maison des vautours La Ferme Caussenarde Sauna, hammam et bain bouillonnant (\u00e0 20 min de la r\u00e9sidence).<\/p><\/div><p>\u00a0<\/p><\/main><\/main><\/article><\/div><\/header>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4afd1e08 e-con-full e-flex e-con e-parent\" data-id=\"4afd1e08\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccf5577 elementor-widget elementor-widget-text-editor\" data-id=\"ccf5577\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tA lire aussi :\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c7db2ea elementor-widget elementor-widget-text-editor\" data-id=\"4c7db2ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.azureva-vacances.com\/fr\/destinations\/sejours-a-theme-vacances-france\/3-idees-vacances-nature\/\"><span data-sheets-root=\"1\">3 id\u00e9es pour des vacances nature<\/span><\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29550cbc elementor-widget elementor-widget-text-editor\" data-id=\"29550cbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.azureva-vacances.com\/fr\/destinations\/sejours-a-theme-vacances-france\/sejour-nature-et-patrimoine\/\"><span data-sheets-root=\"1\">Des s\u00e9jours nature et patrimoine<\/span><\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7be166b elementor-widget elementor-widget-text-editor\" data-id=\"7be166b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.azureva-vacances.com\/fr\/destinations\/campagne\/vacances-campagne-fournols-auvergne\/\"><span data-sheets-root=\"1\">Vacances en ferme p\u00e9dagogique \u00e0 la campagne : r\u00e9veillez votre nature \u00e0 Fournols d\u2019Auvergne !<\/span><\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6ab3ad elementor-widget elementor-widget-text-editor\" data-id=\"b6ab3ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.azureva-vacances.com\/fr\/destinations\/sejours-a-theme-vacances-france\/location-vacances-parcs-naturels\/\"><span data-sheets-root=\"1\">Nos locations vacances proches de parcs naturels<\/span><\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-828eede e-flex e-con-boxed e-con e-parent\" data-id=\"828eede\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3bf737e elementor-widget elementor-widget-shortcode\" data-id=\"3bf737e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d190d1f elementor-widget elementor-widget-html\" data-id=\"d190d1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\r\n.gs-review-username {\r\n  visibility: hidden;\r\n}\r\n.gs-review-username.gs-anonymized {\r\n  visibility: visible;\r\n}\r\n<\/style>\r\n\r\n<script>\r\n(function() {\r\n  function anonymize() {\r\n    var names = document.querySelectorAll('.gs-review-username:not(.gs-anonymized)');\r\n    names.forEach(function(el) {\r\n      var parts = el.textContent.trim().split(\/\\s+\/);\r\n      if (parts.length >= 2) {\r\n        \/\/ Format Guest Suite : \"NOM Pr\u00e9nom\" \u2192 \"N. Pr\u00e9nom\"\r\n        var initiale = parts[0].charAt(0).toUpperCase() + '.';\r\n        var prenom = parts.slice(1).map(function(p) {\r\n          return p.charAt(0).toUpperCase() + p.slice(1).toLowerCase();\r\n        }).join(' ');\r\n        el.textContent = initiale + ' ' + prenom;\r\n      }\r\n      el.classList.add('gs-anonymized');\r\n    });\r\n  }\r\n\r\n  var observer = new MutationObserver(anonymize);\r\n  observer.observe(document.body || document.documentElement, {\r\n    childList: true,\r\n    subtree: true\r\n  });\r\n\r\n  document.addEventListener('DOMContentLoaded', anonymize);\r\n})();\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"template":"","activity-leasure":[176,272,273,274,275,276],"class_list":["post-11470","fiche-ete","type-fiche-ete","status-publish","hentry","activity-leasure-decouverte-du-territoire-la-malene","activity-leasure-descente-des-gorges-en-canoe","activity-leasure-la-descente-en-barque-des-bateliers","activity-leasure-randonnees-et-panoramas","activity-leasure-sports-de-pleine-nature","activity-leasure-villages-et-terroir-lozeriens"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>H\u00f4tel Les Bateliers \u00e0 La Mal\u00e8ne dans les Gorges du Tarn<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez notre h\u00f4tel \u00e0 La Mal\u00e8ne dans les Gorges du Tarn. Un h\u00f4tel id\u00e9al pour des vacances de charme \u00e0 proximit\u00e9 des rives du Tarn !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.azureva-vacances.com\/fr\/hebergement\/hotel-gorges-du-tarn\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"H\u00f4tel Les Bateliers \u00e0 La Mal\u00e8ne dans les Gorges du Tarn\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez notre h\u00f4tel \u00e0 La Mal\u00e8ne dans les Gorges du Tarn. Un h\u00f4tel id\u00e9al pour des vacances de charme \u00e0 proximit\u00e9 des rives du Tarn !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.azureva-vacances.com\/fr\/hebergement\/hotel-gorges-du-tarn\/\" \/>\n<meta property=\"og:site_name\" content=\"Azureva Vacances en France\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AzurevaVacances\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-31T12:42:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.azureva-vacances.com\/wp-content\/uploads\/2025\/02\/583d4a0350add_vacances-velo-la-malene-150x150.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/hebergement\\\/hotel-gorges-du-tarn\\\/\",\"url\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/hebergement\\\/hotel-gorges-du-tarn\\\/\",\"name\":\"H\u00f4tel Les Bateliers \u00e0 La Mal\u00e8ne dans les Gorges du Tarn\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/hebergement\\\/hotel-gorges-du-tarn\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/hebergement\\\/hotel-gorges-du-tarn\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.azureva-vacances.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/583d4a0350add_vacances-velo-la-malene-150x150.jpg\",\"datePublished\":\"2025-02-25T14:42:52+00:00\",\"dateModified\":\"2026-08-31T12:42:04+00:00\",\"description\":\"D\u00e9couvrez notre h\u00f4tel \u00e0 La Mal\u00e8ne dans les Gorges du Tarn. Un h\u00f4tel id\u00e9al pour des vacances de charme \u00e0 proximit\u00e9 des rives du Tarn !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/hebergement\\\/hotel-gorges-du-tarn\\\/#breadcrumb\"},\"inLanguage\":\"fr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/hebergement\\\/hotel-gorges-du-tarn\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr\",\"@id\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/hebergement\\\/hotel-gorges-du-tarn\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.azureva-vacances.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/583d4a0350add_vacances-velo-la-malene-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/www.azureva-vacances.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/583d4a0350add_vacances-velo-la-malene-150x150.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/hebergement\\\/hotel-gorges-du-tarn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gorges du Tarn &#8211; Les Bateliers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/\",\"name\":\"Azureva Vacances\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/#organization\",\"name\":\"Azureva Vacances\",\"url\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr\",\"@id\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.azureva-vacances.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.azureva-vacances.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logo.svg\",\"caption\":\"Azureva Vacances\"},\"image\":{\"@id\":\"https:\\\/\\\/www.azureva-vacances.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AzurevaVacances\\\/\",\"https:\\\/\\\/www.instagram.com\\\/azurevavacances\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@azureva_vacances\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/vacancesazureva\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/azureva\\\/mycompany\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"H\u00f4tel Les Bateliers \u00e0 La Mal\u00e8ne dans les Gorges du Tarn","description":"D\u00e9couvrez notre h\u00f4tel \u00e0 La Mal\u00e8ne dans les Gorges du Tarn. Un h\u00f4tel id\u00e9al pour des vacances de charme \u00e0 proximit\u00e9 des rives du Tarn !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.azureva-vacances.com\/fr\/hebergement\/hotel-gorges-du-tarn\/","og_locale":"fr_FR","og_type":"article","og_title":"H\u00f4tel Les Bateliers \u00e0 La Mal\u00e8ne dans les Gorges du Tarn","og_description":"D\u00e9couvrez notre h\u00f4tel \u00e0 La Mal\u00e8ne dans les Gorges du Tarn. Un h\u00f4tel id\u00e9al pour des vacances de charme \u00e0 proximit\u00e9 des rives du Tarn !","og_url":"https:\/\/www.azureva-vacances.com\/fr\/hebergement\/hotel-gorges-du-tarn\/","og_site_name":"Azureva Vacances en France","article_publisher":"https:\/\/www.facebook.com\/AzurevaVacances\/","article_modified_time":"2026-08-31T12:42:04+00:00","og_image":[{"url":"https:\/\/www.azureva-vacances.com\/wp-content\/uploads\/2025\/02\/583d4a0350add_vacances-velo-la-malene-150x150.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.azureva-vacances.com\/fr\/hebergement\/hotel-gorges-du-tarn\/","url":"https:\/\/www.azureva-vacances.com\/fr\/hebergement\/hotel-gorges-du-tarn\/","name":"H\u00f4tel Les Bateliers \u00e0 La Mal\u00e8ne dans les Gorges du Tarn","isPartOf":{"@id":"https:\/\/www.azureva-vacances.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.azureva-vacances.com\/fr\/hebergement\/hotel-gorges-du-tarn\/#primaryimage"},"image":{"@id":"https:\/\/www.azureva-vacances.com\/fr\/hebergement\/hotel-gorges-du-tarn\/#primaryimage"},"thumbnailUrl":"https:\/\/www.azureva-vacances.com\/wp-content\/uploads\/2025\/02\/583d4a0350add_vacances-velo-la-malene-150x150.jpg","datePublished":"2025-02-25T14:42:52+00:00","dateModified":"2026-08-31T12:42:04+00:00","description":"D\u00e9couvrez notre h\u00f4tel \u00e0 La Mal\u00e8ne dans les Gorges du Tarn. Un h\u00f4tel id\u00e9al pour des vacances de charme \u00e0 proximit\u00e9 des rives du Tarn !","breadcrumb":{"@id":"https:\/\/www.azureva-vacances.com\/fr\/hebergement\/hotel-gorges-du-tarn\/#breadcrumb"},"inLanguage":"fr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.azureva-vacances.com\/fr\/hebergement\/hotel-gorges-du-tarn\/"]}]},{"@type":"ImageObject","inLanguage":"fr","@id":"https:\/\/www.azureva-vacances.com\/fr\/hebergement\/hotel-gorges-du-tarn\/#primaryimage","url":"https:\/\/www.azureva-vacances.com\/wp-content\/uploads\/2025\/02\/583d4a0350add_vacances-velo-la-malene-150x150.jpg","contentUrl":"https:\/\/www.azureva-vacances.com\/wp-content\/uploads\/2025\/02\/583d4a0350add_vacances-velo-la-malene-150x150.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.azureva-vacances.com\/fr\/hebergement\/hotel-gorges-du-tarn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.azureva-vacances.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Gorges du Tarn &#8211; Les Bateliers"}]},{"@type":"WebSite","@id":"https:\/\/www.azureva-vacances.com\/fr\/#website","url":"https:\/\/www.azureva-vacances.com\/fr\/","name":"Azureva Vacances","description":"","publisher":{"@id":"https:\/\/www.azureva-vacances.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.azureva-vacances.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr"},{"@type":"Organization","@id":"https:\/\/www.azureva-vacances.com\/fr\/#organization","name":"Azureva Vacances","url":"https:\/\/www.azureva-vacances.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr","@id":"https:\/\/www.azureva-vacances.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.azureva-vacances.com\/wp-content\/uploads\/2025\/01\/logo.svg","contentUrl":"https:\/\/www.azureva-vacances.com\/wp-content\/uploads\/2025\/01\/logo.svg","caption":"Azureva Vacances"},"image":{"@id":"https:\/\/www.azureva-vacances.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AzurevaVacances\/","https:\/\/www.instagram.com\/azurevavacances\/","https:\/\/www.tiktok.com\/@azureva_vacances","https:\/\/www.youtube.com\/user\/vacancesazureva","https:\/\/www.linkedin.com\/company\/azureva\/mycompany\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.azureva-vacances.com\/fr\/wp-json\/wp\/v2\/fiche-ete\/11470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.azureva-vacances.com\/fr\/wp-json\/wp\/v2\/fiche-ete"}],"about":[{"href":"https:\/\/www.azureva-vacances.com\/fr\/wp-json\/wp\/v2\/types\/fiche-ete"}],"version-history":[{"count":5,"href":"https:\/\/www.azureva-vacances.com\/fr\/wp-json\/wp\/v2\/fiche-ete\/11470\/revisions"}],"predecessor-version":[{"id":287103,"href":"https:\/\/www.azureva-vacances.com\/fr\/wp-json\/wp\/v2\/fiche-ete\/11470\/revisions\/287103"}],"wp:attachment":[{"href":"https:\/\/www.azureva-vacances.com\/fr\/wp-json\/wp\/v2\/media?parent=11470"}],"wp:term":[{"taxonomy":"activity-leasure","embeddable":true,"href":"https:\/\/www.azureva-vacances.com\/fr\/wp-json\/wp\/v2\/activity-leasure?post=11470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}